{"id":134225,"date":"2021-09-01T08:34:14","date_gmt":"2021-09-01T11:34:14","guid":{"rendered":"http:\/\/www.vivacquaadvogados.com\/lei-no-14-193-21-sociedade-anonima-de-futebol\/"},"modified":"2021-10-26T08:35:03","modified_gmt":"2021-10-26T11:35:03","slug":"lei-no-14-193-21-sociedade-anonima-de-futebol","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/lei-no-14-193-21-sociedade-anonima-de-futebol\/","title":{"rendered":"LEI N\u00ba 14.193\/21 &#8211; SOCIEDADE ANONIMA DE FUTEBOL"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A Receita Federal atrav\u00e9s da Solu\u00e7\u00e3o de Consulta do COSIT n\u00ba 43\/21 esclareceu que est\u00e1 sujeita \u00e0 incid\u00eancia de Imposto sobre a Renda na Fonte &#8211; IRRF com uma al\u00edquota de 15% ou 25%, a depender do domic\u00edlio ou resid\u00eancia do benefici\u00e1rio, as import\u00e2ncias pagas, creditadas, entregues, empregadas ou remetidas a residente ou domiciliado no exterior em contrapresta\u00e7\u00e3o pelo direito de comercializa\u00e7\u00e3o ou distribui\u00e7\u00e3o de software, para revenda a consumidor final, sob o argumento de que o fato gerador \u00e9 a aquisi\u00e7\u00e3o de disponibilidade econ\u00f4mica ou jur\u00eddica de renda e ocorre no pagamento, cr\u00e9dito, emprego, entrega ou remessa de rendimento, o que se verificar primeiro, por fonte situada no Pa\u00eds.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A mencionada lei institui a Sociedade An\u00f4nima do Futebol e disp\u00f5e sobre normas de constitui\u00e7\u00e3o, governan\u00e7a, controle e transpar\u00eancia, assim como meios de financiamento da atividade futebol\u00edstica.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Com inova\u00e7\u00e3o legislativa, a Sociedade An\u00f4nima do Futebol poder\u00e1 ser constitu\u00edda por iniciativa de pessoa natural, jur\u00eddica ou de fundo de investimento, bem como por meio de opera\u00e7\u00f5es societ\u00e1rias mediante a transforma\u00e7\u00e3o da associa\u00e7\u00e3o civil em sociedade an\u00f4nima.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A Lei da Sociedade An\u00f4nima no Futebol representa avan\u00e7os para o futebol no Pa\u00eds, sendo certo que possibilitar\u00e1 o fortalecimento econ\u00f4mico das entidades, suprindo a car\u00eancia de incentivos, atraso normativo e pr\u00e1tico dentre outros benef\u00edcios.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-134225","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134225\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=134225"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134225\/revisions\/"}],"predecessor-version":[{"id":134226,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134225\/revisions\/134226\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=134225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=134225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=134225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}