{"id":134645,"date":"2021-12-08T11:29:38","date_gmt":"2021-12-08T14:29:38","guid":{"rendered":"http:\/\/www.vivacquaadvogados.com\/stj-resp-1-805-226-sp-issqn-fato-gerador-embarcacoes-estrageiras-nao-ocorrencia\/"},"modified":"2022-01-27T10:30:43","modified_gmt":"2022-01-27T13:30:43","slug":"stj-resp-1-805-226-sp-issqn-fato-gerador-embarcacoes-estrageiras-nao-ocorrencia","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/stj-resp-1-805-226-sp-issqn-fato-gerador-embarcacoes-estrageiras-nao-ocorrencia\/","title":{"rendered":"STJ \u2013 RESP 1.805.226-SP &#8211; ISSQN &#8211; FATO GERADOR &#8211; EMBARCA\u00c7\u00d5ES ESTRAGEIRAS \u2013 N\u00c3O OCORRENCIA"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A 1\u00aa Turma do STJ ao julgar o citado recurso sobre a exporta\u00e7\u00e3o de servi\u00e7os, se manifestou no sentido de que \u00e9 &#8220;condi\u00e7\u00e3o para que haja exporta\u00e7\u00e3o de servi\u00e7os desenvolvidos no Brasil que o resultado da atividade contratada n\u00e3o se verifique dentro do nosso Pa\u00eds, sendo de suma import\u00e2ncia, por conseguinte, a compreens\u00e3o do termo &#8216;resultado&#8217; como disposto no par\u00e1grafo \u00fanico do art. 2\u00ba&#8221;.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Por se tratar de embarca\u00e7\u00f5es que ostentariam o status de territ\u00f3rio estrangeiro, caracterizada estaria a exporta\u00e7\u00e3o do servi\u00e7o para o exterior do Pa\u00eds, capaz de arredar a incid\u00eancia do ISSQN, como disp\u00f5e o art. 2\u00ba, I, da LC 116\/2003. Tal percep\u00e7\u00e3o, em verdade, exsurge infirmada pela literalidade do art. 3\u00ba, \u00a7 3\u00ba, da LC 116\/2003, que assim preceitua: &#8220;Considera-se ocorrido o fato gerador do imposto no local do estabelecimento prestador nos servi\u00e7os executados em \u00e1guas mar\u00edtimas&#8230;&#8221;.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Logo, se constata que o legislador, para fins de incid\u00eancia do tributo, n\u00e3o fez qualquer distin\u00e7\u00e3o quanto \u00e0 nacionalidade da embarca\u00e7\u00e3o ou do equipamento atendidos pelo servi\u00e7o, n\u00e3o cabendo ao int\u00e9rprete, portanto, empreender tal distin\u00e7\u00e3o.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-134645","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134645\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=134645"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134645\/revisions\/"}],"predecessor-version":[{"id":134646,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134645\/revisions\/134646\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=134645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=134645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=134645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}