{"id":134650,"date":"2021-12-15T10:32:05","date_gmt":"2021-12-15T13:32:05","guid":{"rendered":"http:\/\/www.vivacquaadvogados.com\/icms-rio-de-janeiro-regime-especial-de-apuracao-vigencia-temporaria\/"},"modified":"2022-01-27T10:32:58","modified_gmt":"2022-01-27T13:32:58","slug":"icms-rio-de-janeiro-regime-especial-de-apuracao-vigencia-temporaria","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/icms-rio-de-janeiro-regime-especial-de-apuracao-vigencia-temporaria\/","title":{"rendered":"ICMS \u2013 RIO DE JANEIRO \u2013 REGIME ESPECIAL DE APURA\u00c7\u00c3O \u2013 VIG\u00caNCIA TEMPOR\u00c1RIA"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Os estabelecimentos comerciais como bares, restaurantes, entre outros, podem optar pela redu\u00e7\u00e3o da base de c\u00e1lculo do ICMS, de forma que a carga tribut\u00e1ria efetiva resulte no percentual de 3% sobre a receita tribut\u00e1vel.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A op\u00e7\u00e3o por tal regime especial poder\u00e1 ser realizada em substitui\u00e7\u00e3o ao regime normal de apura\u00e7\u00e3o e recolhimento do imposto e veda o aproveitamento de quaisquer cr\u00e9ditos do imposto.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">O contribuinte optante pelo Simples Nacional n\u00e3o poder\u00e1 usufruir do citado benef\u00edcio. Tal regime tribut\u00e1rio possui vid\u00eancia at\u00e9 a data de 31\/12\/32.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-134650","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134650\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=134650"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134650\/revisions\/"}],"predecessor-version":[{"id":134651,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/134650\/revisions\/134651\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=134650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=134650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=134650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}