{"id":135661,"date":"2023-03-03T09:11:16","date_gmt":"2023-03-03T12:11:16","guid":{"rendered":"http:\/\/www.vivacquaadvogados.com\/stj-resp-1707468-recuperacao-judicial-e-falencia-confissao\/"},"modified":"2023-03-24T08:12:10","modified_gmt":"2023-03-24T11:12:10","slug":"stj-resp-1707468-recuperacao-judicial-e-falencia-confissao","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/stj-resp-1707468-recuperacao-judicial-e-falencia-confissao\/","title":{"rendered":"STJ \u2013 REsp 1707468 \u2013 RECUPERA\u00c7\u00c3O JUDICIAL E FAL\u00caNCIA \u2013 CONFISS\u00c3O"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">O Superior Tribunal de justi\u00e7a, ao julgar o REsp em refer\u00eancia, firmou o entendimento de que a confiss\u00e3o da empresa em recupera\u00e7\u00e3o judicial sobre a impossibilidade de seguir cumprindo o respectivo plano n\u00e3o configura o seu real descumprimento e, portanto, n\u00e3o autoriza, por si s\u00f3, a convola\u00e7\u00e3o em fal\u00eancia.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Destacou-se que \u00e9 poss\u00edvel modificar o plano depois do prazo de dois anos, quando n\u00e3o h\u00e1 senten\u00e7a de encerramento da recupera\u00e7\u00e3o. Por outro lado \u2013 observou \u2013, ocorrendo o descumprimento de qualquer obriga\u00e7\u00e3o do plano no per\u00edodo de supervis\u00e3o judicial, a lei permite a convola\u00e7\u00e3o da recupera\u00e7\u00e3o em fal\u00eancia.<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-135661","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135661\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=135661"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135661\/revisions\/"}],"predecessor-version":[{"id":135662,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135661\/revisions\/135662\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=135661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=135661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=135661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}