{"id":135754,"date":"2023-04-28T08:40:55","date_gmt":"2023-04-28T11:40:55","guid":{"rendered":"http:\/\/www.vivacquaadvogados.com\/stf-adc-49-icms-nao-incidencia-do-nas-transferencias-conclusao-do-julgamento\/"},"modified":"2023-05-03T08:41:52","modified_gmt":"2023-05-03T11:41:52","slug":"stf-adc-49-icms-nao-incidencia-do-nas-transferencias-conclusao-do-julgamento","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/stf-adc-49-icms-nao-incidencia-do-nas-transferencias-conclusao-do-julgamento\/","title":{"rendered":"STF &#8211; ADC 49 &#8211; ICMS &#8211; N\u00c3O INCID\u00caNCIA DO NAS TRANSFER\u00caNCIAS &#8211; CONCLUS\u00c3O DO JULGAMENTO"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:0px;--awb-margin-bottom:80px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-text-transform:none;\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Em 19\/04\/23, os Ministros do STF conclu\u00edram o julgamento dos Embargos de Declara\u00e7\u00e3o opostos na ADC n\u00ba 49, sobre a necessidade do estorno e transfer\u00eancias dos cr\u00e9ditos e a modula\u00e7\u00e3o dos efeitos da decis\u00e3o que declarou inconstitucional a incid\u00eancia do ICMS nas transfer\u00eancias de mercadorias entre estabelecimentos da mesma empresa.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Em Plen\u00e1rio Virtual, a maioria dos ministros seguiu o voto do Relator, Min. Edson Fachin, consolidando o entendimento quanto a:<\/p>\n<ol style=\"text-align: left; font-size: 20px; line-height: 30px;\">\n<li>inviabilidade do estorno dos cr\u00e9ditos, ante a observ\u00e2ncia do princ\u00edpio da n\u00e3o cumulatividade, e;<\/li>\n<li>na modula\u00e7\u00e3o, ficou definido que os efeitos da ADC 49 tenha \u201c&#8230; tenha efic\u00e1cia pr\u00f3-futuro a partir do exerc\u00edcio financeiro de 2024, ressalvados os processos administrativos e judiciais pendentes de conclus\u00e3o at\u00e9 a data de publica\u00e7\u00e3o da ata de julgamento da decis\u00e3o de m\u00e9rito. Exaurido o prazo sem que os Estados disciplinem a transfer\u00eancia de cr\u00e9ditos de ICMS entre estabelecimentos de mesmo titular, fica reconhecido o direito dos sujeitos passivos de transferirem tais cr\u00e9ditos\u201d.<\/li>\n<\/ol>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-135754","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135754\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=135754"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135754\/revisions\/"}],"predecessor-version":[{"id":135755,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/135754\/revisions\/135755\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=135754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=135754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=135754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}