{"id":136756,"date":"2024-07-26T09:39:00","date_gmt":"2024-07-26T12:39:00","guid":{"rendered":"https:\/\/www.vivacquaadvogados.com\/solucao-de-consulta-cosit-no-116-24-irrf-aliquota-zero-feiras-de-negocio-online-inaplicabilidade\/"},"modified":"2024-07-26T09:39:14","modified_gmt":"2024-07-26T12:39:14","slug":"solucao-de-consulta-cosit-no-116-24-irrf-aliquota-zero-feiras-de-negocio-online-inaplicabilidade","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/solucao-de-consulta-cosit-no-116-24-irrf-aliquota-zero-feiras-de-negocio-online-inaplicabilidade\/","title":{"rendered":"Solu\u00e7\u00e3o de Consulta Cosit n\u00ba 116\/24 \u2013 IRRF &#8211; al\u00edquota zero &#8211; feiras de neg\u00f3cio online \u2013 inaplicabilidade"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">Pela mencionada solu\u00e7\u00e3o de consulta, a Receita Federal se manifestou no sentido de que os eventos online n\u00e3o est\u00e3o sujeitos \u00e0 al\u00edquota zero do Imposto de Renda Retido na Fonte \u2013 IRRF, prevista no artigo 1\u00b0, inciso III, al\u00ednea \u201ca\u201d da Lei 9481\/1997, para feiras e rodadas de neg\u00f3cios internacionais.<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A solu\u00e7\u00e3o de consulta se deu no sentido de que os eventos online n\u00e3o est\u00e3o sujeitos \u00e0 al\u00edquota zero do Imposto de Renda Retido na Fonte &#8211; IRRF prevista para feiras e rodadas de neg\u00f3cios internacionais, bem como os pagamentos relacionados a eventos presenciais em solo brasileiro. De igual forma, n\u00e3o s\u00e3o beneficiados pelo regime da al\u00edquota zero do IR Fonte, eventos que sejam considerados rodadas de neg\u00f3cios que podem resultar em exporta\u00e7\u00f5es de produtos nacionais.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-136756","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136756\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=136756"}],"version-history":[{"count":1,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136756\/revisions\/"}],"predecessor-version":[{"id":136757,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136756\/revisions\/136757\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=136756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=136756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=136756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}