{"id":136896,"date":"2025-03-20T12:55:38","date_gmt":"2025-03-20T15:55:38","guid":{"rendered":"https:\/\/www.vivacquaadvogados.com\/lei-no-14-286-resolucao-bcb-no-278-22-declaracao-anual-de-sociedades-receptoras-de-capital-estrangeiro-prazo-de-entrega\/"},"modified":"2025-03-20T13:59:41","modified_gmt":"2025-03-20T16:59:41","slug":"lei-no-14-286-resolucao-bcb-no-278-22-declaracao-anual-de-sociedades-receptoras-de-capital-estrangeiro-prazo-de-entrega","status":"publish","type":"post","link":"https:\/\/www.vivacquaadvogados.com\/es\/lei-no-14-286-resolucao-bcb-no-278-22-declaracao-anual-de-sociedades-receptoras-de-capital-estrangeiro-prazo-de-entrega\/","title":{"rendered":"LEI N\u00ba 14.286 &#8211; RESOLU\u00c7\u00c3O BCB N\u00ba 278\/22 &#8211; DECLARA\u00c7\u00c3O ANUAL DE SOCIEDADES RECEPTORAS DE CAPITAL ESTRANGEIRO \u2013- PRAZO DE ENTREGA"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling gradient-container-1\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: left; font-size: 20px; line-height: 30px;\">O texto atual da Resolu\u00e7\u00e3o BCB n\u00ba 278\/22, a qual regulamenta a Lei n\u00ba 14.286\/21, fixa que os receptores de investimento estrangeiro direto tem at\u00e9 31\/03\/2025 para entrega da Declara\u00e7\u00e3o Anual de Sociedades Receptoras de Capital Estrangeiro, referente ao ano-base 2024 ao Banco Central do Brasil (BCB) atrav\u00e9s do Sistema de Presta\u00e7\u00e3o de Informa\u00e7\u00e3o de Capital Estrangeiro Direto (SCE-IED).<\/p>\n<p style=\"text-align: left; font-size: 20px; line-height: 30px;\">A referida declara\u00e7\u00e3o deve ser entregue somente pelas pessoas jur\u00eddicas sediadas no Pa\u00eds que em 31 de dezembro do ano-base, tinham participa\u00e7\u00e3o direta de n\u00e3o residentes em seu capital social, em qualquer montante e possu\u00edam ativos totais em valor igual ou superior a R$ 100 milh\u00f5es, sob pena de multa que pode chegar a R$ 250.000,00, como previsto na Resolu\u00e7\u00e3o BCB n\u00ba 131\/21.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-136896","post","type-post","status-publish","format-standard","hentry","category-publicaciones_es"],"_links":{"self":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136896\/"}],"collection":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/comments\/?post=136896"}],"version-history":[{"count":2,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136896\/revisions\/"}],"predecessor-version":[{"id":136902,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/posts\/136896\/revisions\/136902\/"}],"wp:attachment":[{"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/media\/?parent=136896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/categories\/?post=136896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vivacquaadvogados.com\/es\/wp-json\/wp\/v2\/tags\/?post=136896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}